{"id":56910,"date":"2025-12-03T00:19:34","date_gmt":"2025-12-03T03:19:34","guid":{"rendered":"https:\/\/simstime.net\/?p=56910"},"modified":"2025-12-17T01:12:28","modified_gmt":"2025-12-17T04:12:28","slug":"the-sims-4-anuncia-kits-do-bob-esponja","status":"publish","type":"post","link":"https:\/\/simstime.net\/pl\/2025\/12\/03\/the-sims-4-anuncia-kits-do-bob-esponja\/","title":{"rendered":"The Sims 4 Anuncia Kits do Bob Esponja"},"content":{"rendered":"<p>Isso n\u00e3o \u00e9 uma pegadinha! A EA acaba de anunciar uma colabora\u00e7\u00e3o oficial entre o The Sims 4 e o Bob Esponja Cal\u00e7a Quadrada, trazendo diretamente da Fenda do Biqu\u00edni, e por tempo limitado, dois pacotes que transformar\u00e3o completamente as casas dos seus Sims. <\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Prepare-se para a ic\u00f4nica casa abacaxi, m\u00f3veis tem\u00e1ticos, objetos exclusivos e at\u00e9 itens especiais de um novo evento de jogo est\u00e3o chegando.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:28px\">\u00cdndice<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"#1\">The Sims 4 Mergulha na Fenda do Biqu\u00edni<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#2\">The Sims 4 Kit Casa do Bob Esponja<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#3\">The Sims 4 Kit Quarto Infantil do Bob Esponja<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#4\">Evento de Login Especial de Fim de Ano<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#5\">Disponibilidade<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1\" style=\"font-size:28px\">The Sims 4 Mergulha na Fenda do Biqu\u00edni<\/h2>\n\n\n\n<p>Estou pronto! Estou pronto! Estou pronto!<\/p>\n\n\n\n<p>Aten\u00e7\u00e3o, f\u00e3s do <em>Bob Esponja Cal\u00e7a Quadrada<\/em>: seus Sims agora podem trazer \u266b <em>um abacaxi do fundo do mar<\/em> \u266b para suas vizinhan\u00e7as o pacote por tempo limitado <strong>Bundle Fenda do Biqu\u00edni<\/strong>, que inclui o <strong>The Sims 4 Kit Casa do Bob Sponja<\/strong> e o <strong>The Sims 4 Kit Quarto Infantil do Bob Esponja<\/strong>.<\/p>\n\n\n\n<p>Por tempo limitado, a <strong><strong>Bundle Fenda do Biqu\u00edni<\/strong><\/strong> estar\u00e1 dispon\u00edvel at\u00e9 o dia <strong>3 de mar\u00e7o de 2026<\/strong>, oferecendo acesso a <strong>tr\u00eas itens exclusivos<\/strong>, al\u00e9m de dois Kits! Promova encontros infantis no <strong>Playground do Holand\u00eas Voador<\/strong>, toque com estilo na <strong>Guitarra Goofy Goober<\/strong>, ou adicione um toque divertido \u00e0 sua decora\u00e7\u00e3o com o <strong>Aqu\u00e1rio da Rua das Conchas do Bob Esponja<\/strong>.<\/p>\n\n\n\n<p>Com esses Kits, voc\u00ea pode construir sua pr\u00f3pria casa-abacaxi ic\u00f4nica, criar um quarto totalmente inspirado em Bob Esponja e adicionar um toque n\u00e1utico cheio de magia para dar \u00e0s casas dos Sims um ar de <strong>F.U.N.<\/strong> de verdade!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-1024x576.webp\" alt=\"\" class=\"wp-image-56916\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2\" style=\"font-size:24px\">The Sims 4 Kit Casa do Bob Esponja<\/h3>\n\n\n\n<p>Entre no clima divertido da casa de fruta submarina mais famosa do mundo com o <strong><strong>The Sims 4 Kit Casa do Bob Sponja<\/strong><\/strong>. Os jogadores podem criar sua pr\u00f3pria vers\u00e3o do endere\u00e7o <strong>Rua das Conchas 124<\/strong>, usando revestimentos, paredes e telhados do <em>Abacaxi do Fundo do Mar<\/em> <em>Pineapple Under The Sea<\/em>, finalizados com o ador\u00e1vel <strong>Pineapple Topper<\/strong>. Complete o visual com novos pisos e pap\u00e9is de parede, como <strong>Revestimento de A\u00e7o For\u00e7ado<\/strong>, <strong>Estampa de Blocos de Bambu<\/strong> e o piso <strong>Areia Banhada de Sol<\/strong>, trazendo aquele toque SpongeBob que todo Sim merece.<\/p>\n\n\n\n<p>A <strong>Porta Escotilha de A\u00e7o<\/strong>, as <strong>Janelas Olho-de-Boi Porto de Escala<\/strong> e a <strong>Respiro de Bolhas Brilhantes<\/strong> adicionam os detalhes finais a essa arquitetura submarina \u2014 pronta at\u00e9 mesmo para resistir aos Nemat\u00f3ides mais persistentes!<\/p>\n\n\n\n<p>O <strong>The Sims 4 Kit Casa do Bob Esponja<\/strong> est\u00e1 recheado de detalhes l\u00fadicos e m\u00f3veis ic\u00f4nicos que d\u00e3o vida \u00e0 Fenda do Biqu\u00edni, incluindo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>TV Capacete de Mergulho do Bob Esponja:<\/strong> a cl\u00e1ssica TV do abacaxi agora pode decorar a casa do seu Sim.<\/li>\n\n\n\n<li><strong>Mesa Lateral \u201cNo Anzol\u201d<\/strong>: uma mesa com tampo robusto sustentado por ganchos divertidos, perfeita para um toque n\u00e1utico.<\/li>\n\n\n\n<li><strong>Alarme Corneta:<\/strong> um despertador funcional com efeitos sonoros que garante que seu Sim nunca se atrase para o turno no Siri Cascudo!<\/li>\n\n\n\n<li><strong>Cadeira Bote Salva-Vidas<\/strong>: uma cadeira com charme oce\u00e2nico e acolchoamento confort\u00e1vel, ideal para os momentos de reflex\u00e3o.<\/li>\n\n\n\n<li><strong>Cama de Solteiro \u201cEu Estou Pronto!\u201d:<\/strong> feita para Sims que querem come\u00e7ar o dia com energia \u2014 e o bord\u00e3o cl\u00e1ssico do Bob Esponja.<\/li>\n\n\n\n<li><strong>A Grande Concha M\u00e1gica:<\/strong> o or\u00e1culo perfeito para orientar o destino do seu Sim!<\/li>\n\n\n\n<li><strong>Vitrola \u201cEntrando em Greve!\u201d:<\/strong> um toca-discos que vibra com a energia do Lula Molusco e o entusiasmo incans\u00e1vel do Bob Esponja.<\/li>\n\n\n\n<li><strong>Sof\u00e1 Infl\u00e1vel:<\/strong> perfeito para relaxar depois de um longo dia virando Hamb\u00fargueres de Siri.<\/li>\n\n\n\n<li><strong>Cadeira Barril do Bucaneiro:<\/strong> acolchoada e adornada no estilo do tesouro do Sr. Sirigueijo.<\/li>\n\n\n\n<li><strong>Porta do Cors\u00e1rio:<\/strong> uma porta robusta que abre caminho para aventuras dignas de piratas.<\/li>\n\n\n\n<li><strong>Mesa de Jantar do Mestre Cuca:<\/strong> inspirada no lend\u00e1rio Siri Cascudo, ideal para quem leva a culin\u00e1ria mar\u00edtima a s\u00e9rio.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:24px\">Imagens<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-1024x576.webp\" alt=\"\" class=\"wp-image-56917\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3\" style=\"font-size:26px\">The Sims 4 Kit Quarto Infantil do Bob Esponja<\/h3>\n\n\n\n<p>No <strong><strong>The Sims 4 Kit Quarto Infantil do Bob Esponja<\/strong><\/strong>, os jogadores podem criar o quarto perfeito para o pequeno f\u00e3 do Bob Esponja, com m\u00f3veis, brinquedos e acess\u00f3rios tem\u00e1ticos! Desde pe\u00e7as estampadas de abacaxi at\u00e9 p\u00f4steres de personagens e detalhes vindos diretamente da Fenda do Biqu\u00edni \u2014 at\u00e9 o pr\u00f3prio <strong>Siri Cascudo<\/strong> marca presen\u00e7a como brinquedo.<\/p>\n\n\n\n<p>Destaques do Kit incluem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cama Tem\u00e1tica do Bob Esponja:<\/strong> para sonhos bem no estilo Cal\u00e7a Quadrada.<\/li>\n\n\n\n<li><strong>Mesa de Estudos, Mesa de Atividades, Criado-Mudo, C\u00f4moda e Estante Inspirados em Abacaxi:<\/strong> Energia alegre da Fenda do Biqu\u00edni.<\/li>\n\n\n\n<li><strong>Cadeira em Forma de Concha:<\/strong>cConforto suficiente para deixar o Lula Molusco com inveja.<\/li>\n\n\n\n<li><strong>Rel\u00f3gio do Gary e Lumin\u00e1ria \u201cAs Muitas Caras do Gary\u201d<\/strong>: para iluminar e manter o ritmo com o caracol mais amado.<\/li>\n\n\n\n<li><strong>Adesivos de Parede do Bob Esponja e do Patrick:<\/strong> para decorar com alegria.<\/li>\n\n\n\n<li><strong>Casinha de Bonecas do Siri Cascudo:<\/strong> mini r\u00e9plica perfeita para imaginar aventuras de hamb\u00fargueres de siri.<\/li>\n\n\n\n<li><strong>Pel\u00facias do Bob Esponja, Patrick e Sandy:<\/strong> para brincadeiras infinitas!<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:24px\">Imagens<\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"56919\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-1024x576.webp\" alt=\"\" class=\"wp-image-56919\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-4.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"56918\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-1024x576.webp\" alt=\"\" class=\"wp-image-56918\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-imagens-3.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4\" style=\"font-size:26px\">Evento de Login Especial de Fim de Ano<\/h3>\n\n\n\n<p>O que s\u00e3o as festas sem um pouquinho de <em>loucura n\u00e1utica<\/em>? Celebre a temporada com o evento <strong>Enfeite as Palmeiras<\/strong>, dispon\u00edvel de <strong>16 de dezembro de 2025 a 11 de janeiro de 2026<\/strong>. Os jogadores poder\u00e3o desbloquear recompensas exclusivas no The Sims 4, incluindo itens tem\u00e1ticos do Bob Esponja, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Uma nova <strong>receita de Hamb\u00farguer de Siri<\/strong><\/li>\n\n\n\n<li><strong>Variante tem\u00e1tica de celular<\/strong><\/li>\n\n\n\n<li><strong>Moletom com cores inspiradas no Bob Esponja<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Seja para colecionar recompensas festivas ou garantir itens raros do universo Bob Esponja, haver\u00e1 algo para cada jogador!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5\" style=\"font-size:26px\">Disponibilidade<\/h3>\n\n\n\n<p>O <strong>The Sims 4 Bundle Fenda do Biqu\u00edni<\/strong> estar\u00e1 dispon\u00edvel em <strong>4 de dezembro de 2025<\/strong> para PC (EA app), Mac (Origin), Epic Games Store, Steam, PlayStation 4 e 5, Xbox Series X|S e Xbox One.<\/p>\n\n\n\n<p>Os Kits <strong>Casa do Bob Espona<\/strong> e <strong>Quarto Infantil do Bob Esponja<\/strong> tamb\u00e9m poder\u00e3o ser comprados separadamente por <strong>R$ 24,00<\/strong> cada.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"56915\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-726x1024.webp\" alt=\"The Sims 4 Anuncia Kits do Bob Esponja\" class=\"wp-image-56915\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-726x1024.webp 726w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-213x300.webp 213w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-768x1084.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-1089x1536.webp 1089w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3-9x12.webp 9w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-3.webp 1200w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"56914\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-726x1024.webp\" alt=\"The Sims 4 Anuncia Kits do Bob Esponja\" class=\"wp-image-56914\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-726x1024.webp 726w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-213x300.webp 213w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-768x1084.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-1089x1536.webp 1089w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2-9x12.webp 9w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-2.webp 1200w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"1024\" data-id=\"56913\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-726x1024.webp\" alt=\"The Sims 4 Anuncia Kits do Bob Esponja\" class=\"wp-image-56913\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-726x1024.webp 726w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-213x300.webp 213w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-768x1084.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-1089x1536.webp 1089w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1-9x12.webp 9w, https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-capas-1.webp 1200w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A oferta termina em 3 de mar\u00e7o de 2026.<\/p>\n\n\n\n<p>Os Kits requerem o jogo base The Sims 4 (gratuito para download) e todas as atualiza\u00e7\u00f5es.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>E essas s\u00e3o todas as principais informa\u00e7\u00f5es sobre os Kits tem\u00e1ticos do Bob Esponja at\u00e9 o momento.<\/p>\n\n\n\n<p>Fiquem ligados no SimsTime para mais novidades!<\/p>","protected":false},"excerpt":{"rendered":"<p>Isso n\u00e3o \u00e9 uma pegadinha! A EA acaba de anunciar uma colabora\u00e7\u00e3o oficial entre o The Sims 4 e o Bob Esponja Cal\u00e7a Quadrada, trazendo diretamente da Fenda do Biqu\u00edni, e por tempo limitado, dois pacotes que transformar\u00e3o completamente as casas dos seus Sims. Prepare-se para a ic\u00f4nica casa abacaxi, m\u00f3veis tem\u00e1ticos, objetos exclusivos e &hellip;<\/p>","protected":false},"author":7,"featured_media":56912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[530,531,6],"tags":[81,532,127,301,533,7],"class_list":["post-56910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-do-bob-sponja","category-quarto-infantil-do-bob-esponja","category-thesims4","tag-anuncios","tag-casa-do-bob-esponja","tag-destaques","tag-kit","tag-quarto-infantil-do-bob-esponja","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja.webp","author_info":{"display_name":"Weslley","author_link":"https:\/\/simstime.net\/pl\/author\/weslley-luzzi\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja.webp","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja.webp",1200,675,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-150x150.webp",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-300x169.webp",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-768x432.webp",768,432,true],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-1024x576.webp",1024,576,true],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja.webp",1200,675,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja.webp",1200,675,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-18x10.webp",18,10,true],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-220x150.webp",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-390x220.webp",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2025\/12\/the-sims-4-bundle-casa-do-bob-esponja-quarto-infantil-do-bob-esponja-780x470.webp",780,470,true]},"uagb_author_info":{"display_name":"Weslley","author_link":"https:\/\/simstime.net\/pl\/author\/weslley-luzzi\/"},"uagb_comment_info":0,"uagb_excerpt":"Isso n\u00e3o \u00e9 uma pegadinha! A EA acaba de anunciar uma colabora\u00e7\u00e3o oficial entre o The Sims 4 e o Bob Esponja Cal\u00e7a Quadrada, trazendo diretamente da Fenda do Biqu\u00edni, e por tempo limitado, dois pacotes que transformar\u00e3o completamente as casas dos seus Sims. Prepare-se para a ic\u00f4nica casa abacaxi, m\u00f3veis tem\u00e1ticos, objetos exclusivos e&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/posts\/56910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/comments?post=56910"}],"version-history":[{"count":5,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/posts\/56910\/revisions"}],"predecessor-version":[{"id":56924,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/posts\/56910\/revisions\/56924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/media\/56912"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/media?parent=56910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/categories?post=56910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/pl\/wp-json\/wp\/v2\/tags?post=56910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}