{"id":25915,"date":"2021-03-02T08:38:59","date_gmt":"2021-03-02T11:38:59","guid":{"rendered":"https:\/\/simstime.net\/?p=25915"},"modified":"2024-01-28T01:27:28","modified_gmt":"2024-01-28T04:27:28","slug":"the-sims-10-vezes-em-que-o-jogo-foi-bastante-obscuro","status":"publish","type":"post","link":"https:\/\/simstime.net\/fr\/2021\/03\/02\/the-sims-10-vezes-em-que-o-jogo-foi-bastante-obscuro\/","title":{"rendered":"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro"},"content":{"rendered":"<p>O <strong><a href=\"https:\/\/gamerant.com\/sims-series-dark-parts\/\" target=\"_blank\" rel=\"noopener\">GameRant<\/a><\/strong> fez um artigo bastante curioso e divertido falando sobre as ocasi\u00f5es em que a franquia The Sims foi bastante surpreendentemente obscura. Confira!<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #9c58b5;\"><em><span style=\"font-size: 20px;\">The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro<\/span><\/em><\/span><\/h2>\n<p style=\"text-align: center;\"><em>Texto assinado pelo <strong><a href=\"https:\/\/gamerant.com\/sims-series-dark-parts\/\" target=\"_blank\" rel=\"noopener\">GameRant.<\/a><\/strong><\/em><\/p>\n<p>Ao jogar The Sims,<em>\u00a0<\/em>os jogadores provavelmente se concentram em construir casas e jogar com a vida de seus Sims. No entanto, algumas vezes a s\u00e9rie fica mais sombria do que o esperado.\u00a0Ler a descri\u00e7\u00e3o de certas fam\u00edlias revelar\u00e1 que pode haver assassinos em uma vizinhan\u00e7a. Da mesma forma que ler a descri\u00e7\u00e3o de um item revelar\u00e1 um passado sombrio.<\/p>\n<p>Alguns jogos derivados da franquia, como o The Sims Medieval, tamb\u00e9m mostram o lado negro da vida do Sim durante a era medieval.\u00a0Jogar os muitos jogos da s\u00e9rie surpreender\u00e1 o jogador \u00e0s vezes.\u00a0Embora o The Sims seja um simulador de vida, os jogadores provavelmente n\u00e3o\u00a0esperam que eventos sombrios e misteriosos\u00a0aconte\u00e7am.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">10<\/span> \/ <span style=\"font-size: 16px;\">10<\/span><br \/>\nTrotes<\/strong><\/span><span style=\"font-size: 20px;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19610 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2020\/06\/The-Sims-1-Trote.jpg\" alt=\"\" width=\"410\" height=\"206\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2020\/06\/The-Sims-1-Trote.jpg 410w, https:\/\/simstime.net\/wp-content\/uploads\/2020\/06\/The-Sims-1-Trote-300x151.jpg 300w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/strong><\/span><\/p>\n<p>Os jogadores do The Sims 1 certamente se lembrar\u00e3o dos trotes que podem receber. Atender certas liga\u00e7\u00f5es poder\u00e1 ter um tom agourento e uma mensagem amea\u00e7adora. Uma mensagem como &#8220;O fim est\u00e1 pr\u00f3ximo. Fa\u00e7a as prepara\u00e7\u00f5es&#8221;\u00a0\u00e9 o suficiente para preocupar qualquer jogador.<\/p>\n<p>As liga\u00e7\u00f5es acontecem muito entre meia-noite e 8 da manh\u00e3. Embora nada realmente aconte\u00e7a e os jogadores provavelmente se esque\u00e7am disso, os Sims controlados ficar\u00e3o assustados e preocupados. Ningu\u00e9m pode culp\u00e1-los, uma liga\u00e7\u00e3o como essa hora da noite tamb\u00e9m \u00e9 assustadora na vida real.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">9<\/span> \/ <span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Levando os Sims para a Morte<\/strong><\/span><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25922 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-6.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-6.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-6-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/p>\n<p>Normalmente na franquia, os Sims n\u00e3o podem matar outros Sims sem o uso de mods.\u00a0No The Sims Medieval, os jogadores podem finalmente matar outros Sims.\u00a0Isso pode ser feito por meio de um duelo ou envenenamento, mas um monarca tamb\u00e9m pode mandar algu\u00e9m para a morte.<\/p>\n<p>Um monarca n\u00e3o precisa ter um motivo ara condenar algu\u00e9m \u00e0 morte, ele pode escolher qualquer um ao acaso. O Sim condenado ser\u00e1 enviado para o campo e for\u00e7ado a lutar contra um monstro. O Sim pode sobreviver, mas eles podem simplesmente ser enviados de volta para a cova at\u00e9 morrer.<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<hr \/>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">8<\/span><span style=\"font-size: 20px;\"> \/ <\/span><span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Senhora Cl\u00f3ris<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25923 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-7.jpg\" alt=\"\" width=\"594\" height=\"423\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-7.jpg 594w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-7-300x214.jpg 300w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/p>\n<p>Quem nunca tentou fazer algo rom\u00e2ntico e falhou? No The Sims 4 Jardim Rom\u00e2ntico, os jogadores podem encontrar um item chamado &#8220;O capricho da Senhora Cl\u00f3ris&#8221;. O marido da Senhora Cl\u00f3ris, Z\u00e9firo, a cercou com esses muros gigantes enquanto ela dormia na tentativa de ser rom\u00e2ntico.<\/p>\n<p>Isso provou ser fatal, j\u00e1 que a Senhora Cl\u00f3ris n\u00e3o foi capaz de conseguir sair de dentro da onde havia sido presa. Ela acabou morrendo de fome no jardim, com seu marido provavelmente sabendo que ele n\u00e3o poderia fazer nada. Como se isso n\u00e3o bastasse, os jogadores podem comprar a mesma coisa que matou Cl\u00f3ris.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 20px;\"><span style=\"font-size: 24px;\">7 <\/span>\/ <\/span><span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Olivia Espectro, A (Potencial) Assassina<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25919 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-3.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-3.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-3-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>A fam\u00edlia Espectro pode ser encontrada em Estranh\u00f3polis, not\u00e1vel por ter um cemit\u00e9rio atr\u00e1s de sua casa. Ol\u00edvia Espectro \u00e9 mais do que prov\u00e1vel uma assassina, sendo respons\u00e1vel pelas mortes no lote. Suas mem\u00f3rias revelam que ela fez Oba-Oba com a Dona Morte e teve um filho.<\/p>\n<p>Parece que ela se apaixonou pela Dona e queria continuar a v\u00ea-la. Ela se casaria com homens e aparentemente os mataria.\u00a0Sims de servi\u00e7o, como entregadores, empregadas dom\u00e9sticas e carteiros tamb\u00e9m comp\u00f5em o cemit\u00e9rio.<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<hr \/>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">6<\/span> \/ <span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>A Planta-Vaca<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25920 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-4.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-4.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-4-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>Ao longo da franquia, os jogadores podem encontrar a Planta-Vaca. Ela pode ficar com muita fome e tentar comer os Sims. Ela vai colocar um peda\u00e7o de bolo em sua l\u00edngua e e comer qualquer um que tentar agarr\u00e1-lo. Isso matar\u00e1 o Sim e encher\u00e1 suas tetas com leite rejuvenescedor.<\/p>\n<p>Outro Sim pode vir e beber a ess\u00eancia gerada na Planta-Vaca atrav\u00e9s do Sim morto. Dependendo do jogo, isso pode mudar seu humor ou prolongar um pouco sua vida.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">5<\/span> \/ <span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Atacado por Tubar\u00f5es<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25918 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-2.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-2.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-2-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/p>\n<p>A morte no The Sims \u00e9 esperada, com alguns tipos de mortes sendo uma surpresa. Durante o mergulho com snorkel no The Sims 3 Ilha Paradis\u00edaca<em>,<\/em> h\u00e1 uma chance de um Sim ser atacado por tubar\u00f5es. Ser atacado uma vez n\u00e3o \u00e9 fatal, mas ser atacado enquanto h\u00e1 modificadores de humor relacionados ao primeiro ataque \u00e9 fatal.<\/p>\n<p>Ser atacado por um tubar\u00e3o parece bastante brutal. Ser morto por um tubar\u00e3o deixar\u00e1 o fantasma do Sim roxo.<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<hr \/>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">4<\/span><span style=\"font-size: 20px;\"> \/ <\/span><span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Os Alde\u00f5es v\u00e3o Festejar com Goblins<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25924 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-8.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-8.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-8-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>No\u00a0 The Sims Medieval<em>,<\/em> existe uma miss\u00e3o chamada &#8220;Goblins!&#8221;. Os jogadores ter\u00e3o duas op\u00e7\u00f5es para lidar com as criaturas, sendo uma delas chamada de\u00a0 &#8220;Abata os Globins&#8221;. Um cavaleiro ou mago ir\u00e1 para a caverna dos goblins e matar\u00e1 as criaturas.<\/p>\n<p>N\u00e3o termina a\u00ed.\u00a0O povo da aldeia celebrar\u00e1 o massacre com uma festa.\u00a0A detalhe \u00e9 que a comida do banquete s\u00e3o os pr\u00f3prios goblins.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">3<\/span> \/ <span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>O Marido Falecido da Senhorita Rogabaixa<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25916 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>A Senhorita Rugabaixa pode ser encontrada no The Sims 2 Vida Noturna quando os jogadores v\u00e3o ao centro. Ela vai bater com a bolsa em Sims que forem flagrados se beijando ou demonstrando afeto um pelo outro na frente dela. Ela pode ser um inc\u00f4modo enquanto um Sim est\u00e1 em um encontro, mas os jogadores podem perdo\u00e1-la um pouco quando souberem de seu passado.<\/p>\n<p>\u00c9 mais do que prov\u00e1vel que ela fosse casada com um famoso filantropo chamado Robert Rugabaixa. Enquanto ele estava em um evento, um lustre caiu de dois andares sobre nele. A Senhora Rugabaixa teria ficado vi\u00fava inesperadamente, provavelmente sentindo \u00f3dio pelos amantes.<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>\n<hr \/>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">2<\/span><span style=\"font-size: 20px;\"> \/ <\/span><span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>O Palha\u00e7o Tr\u00e1gico<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25921 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-5.jpg\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"740\" height=\"370\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-5.jpg 740w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-5-300x150.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p>Se os jogadores tiverem uma pintura\u00a0do Palha\u00e7o Tr\u00e1gico, ele vir\u00e1 para animar os Sims deprimidos. Infelizmente, o tiro sempre sai pela culatra e deixa o Sim mais triste ainda. H\u00e1 algo muito triste em uma pessoa tentar animar algu\u00e9m e fracassar muito. Especialmente quando o pr\u00f3prio Palha\u00e7o Tr\u00e1gico parece estar deprimido.<\/p>\n<p>Ele aparece em no The Sims 1 e The Sims 4<em>,<\/em> aparecendo para melhorar o \u00e2nimo dos Sims. O palha\u00e7o fez uma participa\u00e7\u00e3o especial em no The Sims 3<em>,<\/em>\u00a0aparecendo como um fantasma em Sunset Valley.\u00a0Apesar de suas tentativas de ser alegre, ele sempre ser\u00e1 um palha\u00e7o triste.<\/p>\n<p><span style=\"font-size: 20px;\"><strong><span style=\"font-size: 24px;\">1<\/span> \/ <span style=\"font-size: 16px;\">10<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: 20px;\"><strong>Laura Caix\u00e3o sendo Separada da Fam\u00edlia<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25917 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png\" alt=\"The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro\" width=\"768\" height=\"432\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png 768w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-300x169.png 300w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-390x220.png 390w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Laura Caix\u00e3o aparece em todos os jogos de alguma forma. No The Sims 2<em>, <\/em>ela foi abduzida por alien\u00edgenas enquanto visitava Don Lot\u00e1rio. Controlar um Sim em Estranh\u00f3polis d\u00e1 a chance de uma Laura Caix\u00e3o surgir, fazendo parecer que ela acabou indo parar na cidade na cidade. No entanto, seu t\u00famulo pode ser encontrado no cen\u00e1rio futurista de Lagos Lunares.<\/p>\n<p>Depois de ser abduzida, Laura nunca mais retorna para sua fam\u00edlia e \u00e9 transportada para outro planeta. Ela sente falta dos acontecimentos da vida de sua fam\u00edlia, como o casamento da filha e o crescimento do filho. Seu marido, Vladmir, tamb\u00e9m tem que seguir em frente com sua vida, envelhecendo sem seu amor.<\/p>","protected":false},"excerpt":{"rendered":"<p>O GameRant fez um artigo bastante curioso e divertido falando sobre as ocasi\u00f5es em que a franquia The Sims foi bastante surpreendentemente obscura. Confira! The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro Texto assinado pelo GameRant. Ao jogar The Sims,\u00a0os jogadores provavelmente se concentram em construir casas e jogar com a vida &hellip;<\/p>","protected":false},"author":5,"featured_media":25917,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[122,6],"tags":[259,7],"class_list":["post-25915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-externos","category-thesims4","tag-artigos-externos","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/fr\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-150x150.png",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-300x169.png",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",18,10,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-220x150.png",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1-390x220.png",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/03\/The-Sims-10-Vezes-em-que-o-Jogo-foi-Bastante-Obscuro-1.png",768,432,false]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/fr\/author\/simstime\/"},"uagb_comment_info":0,"uagb_excerpt":"O GameRant fez um artigo bastante curioso e divertido falando sobre as ocasi\u00f5es em que a franquia The Sims foi bastante surpreendentemente obscura. Confira! The Sims: 10 Vezes em que o Jogo foi Bastante Obscuro Texto assinado pelo GameRant. Ao jogar The Sims,\u00a0os jogadores provavelmente se concentram em construir casas e jogar com a vida\u2026","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/posts\/25915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/comments?post=25915"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/posts\/25915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/media\/25917"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/media?parent=25915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/categories?post=25915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/fr\/wp-json\/wp\/v2\/tags?post=25915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}