{"id":26786,"date":"2021-05-11T07:01:42","date_gmt":"2021-05-11T10:01:42","guid":{"rendered":"https:\/\/simstime.net\/?p=26786"},"modified":"2023-12-28T23:41:19","modified_gmt":"2023-12-29T02:41:19","slug":"novo-mod-de-realismo-para-the-sims-4-the-personality-mod","status":"publish","type":"post","link":"https:\/\/simstime.net\/es\/2021\/05\/11\/novo-mod-de-realismo-para-the-sims-4-the-personality-mod\/","title":{"rendered":"Novo Mod de Realismo para The Sims 4: The Personality Mod"},"content":{"rendered":"<p>A modder <strong><a href=\"https:\/\/modthesims.info\/m\/4928488\" target=\"_blank\" rel=\"noopener\">&#8220;missihissy&#8221;<\/a><\/strong> compartilhou no Mod The Sims a sua mais recente cria\u00e7\u00e3o, o The Personality Mod. Este mod \u00e9 inspirado nas aspira\u00e7\u00f5es do The Sims 2, e tem como promessa adicionar uma nova gama de comportamentos aos Sims do The Sims 4. Confira!<\/p>\n<p><span style=\"font-size: 20px;\"><strong>O Que o The Personality Mod Faz:<\/strong><\/span><\/p>\n<p>O The Personality Mod adiciona 6 tra\u00e7os de recompensa na Loja de Recompensas do The Sims 4. Cada um desses tra\u00e7os \u00e9 inspirado nas seis aspira\u00e7\u00f5es do The Sims 2, que s\u00e3o: Fam\u00edlia, Fortuna, Conhecimento, Prazer, Popularidade e Romance. Cada tra\u00e7o custa 0 Pontos de Satisfa\u00e7\u00e3o, e voc\u00ea pode adicion\u00e1-los em Sims rec\u00e9m criados, direto do Criar Um Sim.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26788 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/thepersonalitymod.jpg\" alt=\"\" width=\"300\" height=\"430\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/thepersonalitymod.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/thepersonalitymod-209x300.jpg 209w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Cada tra\u00e7o tem os seus pr\u00f3\u00b4rios caprichos que s\u00e3o diretamente inspirados nos desejos do The Sims 2. Por causa disso, esses tra\u00e7os agem como uma personalidade b\u00e1sica que influencia os caprichos dos seus Sims.<\/p>\n<p><strong>Exemplo:<\/strong> Um Sim com o tra\u00e7o de Fortuna ter\u00e1 o desejo de ter seu pr\u00f3prio neg\u00f3cio; um Sim com tra\u00e7o de Fam\u00edlia pode querer ter um beb\u00ea ou adotar um cachorro; Um Sim com tra\u00e7o de Conhecimento ficar\u00e1 curioso sobre o sobrenatural etc.<\/p>\n<p><span style=\"font-size: 20px;\"><strong>Os Caprichos:<\/strong><\/span><\/p>\n<p>Embora alguns caprichos originais do The Sims 4 foram excelentes para atender cada tra\u00e7o, senti que muitos estavam faltando. Como resultado, foram criados novos caprichos especificamente para o mod. O The Personality Mod adiciona 40 novos caprichos, cada um associado aos seis tra\u00e7os. Entre esses caprichos, v\u00e1rios est\u00e3o relacionados a carreiras individuais. Cada um deles s\u00f3 aparecer\u00e3o nos Sims que tiverem certas caracter\u00edsticas, ent\u00e3o n\u00e3o se trata de caprichos aleat\u00f3rios.<\/p>\n<hr \/>\n\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t\n<hr \/>\n<p><span style=\"font-size: 20px;\"><strong>Exemplos de ALGUNS dos Caprichos:<\/strong><\/span><\/p>\n<ul>\n<li><em>Seja Abduzido por Aliens, <\/em><\/li>\n<li><em>Tenha seu Pr\u00f3prio Neg\u00f3cio<\/em><\/li>\n<li><em>Tenha um Beb\u00ea<\/em><\/li>\n<li><em>Assistir um Filme com a Fam\u00edlia<\/em><\/li>\n<li><em> Sair da Cidade, Dar Amasso no Closet<\/em><\/li>\n<li><em>Ser Amigo da Fam\u00edlia Quero-Tudo-Que-\u00c9-Seu<\/em><\/li>\n<li><em>Jantar Fora com um Sim<\/em><\/li>\n<li>Pedir para Se Mudar<\/li>\n<\/ul>\n<p><span style=\"font-size: 20px;\"><strong>Compat\u00edvel com Jogo B\u00e1sico, mas Melhor com Pacotes:<\/strong><\/span><\/p>\n<ul>\n<li>Ao trabalho<\/li>\n<li>\u00a1Quedamos?<\/li>\n<li>Urbanitas<\/li>\n<li>Perros y Gatos<\/li>\n<li>Y Las Cuatro Estaciones<\/li>\n<li>\u00a1Rumbo a la Fama!<\/li>\n<li>D\u00edas de Universidad<\/li>\n<li>Escapada Gourmet<\/li>\n<li>Vampiros<\/li>\n<li>Pap\u00e1s y Mam\u00e1s<\/li>\n<li>Reino da Magia<\/li>\n<li>Noche de Bolos<\/li>\n<li>Beb\u00eas<\/li>\n<li>Meu Primeiro Bichinho<\/li>\n<\/ul>\n\n\t\t<div class=\"box info\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span><strong>Atenci\u00f3n:<\/strong> o mod est\u00e1 traduzido para o portugu\u00eas. Para baix\u00e1-lo, clique no bot\u00e3o abaixo.\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n<p style=\"text-align: center;\"><a href=\"https:\/\/sims4dailyplumbob.game.blog\/mods-cc\/mods\/the-personality-mod\/\" target=\"_blank\" class=\"shortc-button big button\" rel=\"noopener\"><span class=\"fa fas fa-download\" aria-hidden=\"true\"><\/span> <strong>Descargar<\/strong><\/a>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 4px;border-top-width:0px;border-bottom-width:0px;\"><\/span>","protected":false},"excerpt":{"rendered":"<p>A modder &#8220;missihissy&#8221; compartilhou no Mod The Sims a sua mais recente cria\u00e7\u00e3o, o The Personality Mod. Este mod \u00e9 inspirado nas aspira\u00e7\u00f5es do The Sims 2, e tem como promessa adicionar uma nova gama de comportamentos aos Sims do The Sims 4. Confira! O Que o The Personality Mod Faz: O The Personality Mod &hellip;<\/p>","protected":false},"author":5,"featured_media":26790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[31,63,6],"tags":[127,64,30,7],"class_list":["post-26786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mods","category-downloads","category-thesims4","tag-destaques","tag-downloads","tag-mods","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/es\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod-150x150.png",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod-300x169.png",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",18,10,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod-220x150.png",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod-390x220.png",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2021\/05\/mod_the_personality_mod.png",768,432,false]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/es\/author\/simstime\/"},"uagb_comment_info":0,"uagb_excerpt":"A modder &#8220;missihissy&#8221; compartilhou no Mod The Sims a sua mais recente cria\u00e7\u00e3o, o The Personality Mod. Este mod \u00e9 inspirado nas aspira\u00e7\u00f5es do The Sims 2, e tem como promessa adicionar uma nova gama de comportamentos aos Sims do The Sims 4. Confira! O Que o The Personality Mod Faz: O The Personality Mod&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/posts\/26786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/comments?post=26786"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/posts\/26786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/media\/26790"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/media?parent=26786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/categories?post=26786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/es\/wp-json\/wp\/v2\/tags?post=26786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}