{"id":9753,"date":"2019-06-18T16:15:03","date_gmt":"2019-06-18T19:15:03","guid":{"rendered":"https:\/\/simstime.com.br\/?p=9753"},"modified":"2024-01-28T01:37:24","modified_gmt":"2024-01-28T04:37:24","slug":"the-sims-4-saiba-tudo-o-que-veio-na-atualizacao-de-junho","status":"publish","type":"post","link":"https:\/\/simstime.net\/en\/2019\/06\/18\/the-sims-4-saiba-tudo-o-que-veio-na-atualizacao-de-junho\/","title":{"rendered":"The Sims 4: Saiba Tudo O que Veio na Atualiza\u00e7\u00e3o de Junho"},"content":{"rendered":"<p>A atualiza\u00e7\u00e3o de junho, lan\u00e7ada hoje (18), adicionou n\u00e3o apenas novas roupas ao The Sims 4, como tamb\u00e9m novos itens, intera\u00e7\u00f5es e at\u00e9 mesmo novas carreiras. Confira abaixo tudo o que chegou ao jogo:<\/p>\n<h4 style=\"text-align: center;\"><strong><span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 8px;border-top-width:0px;border-bottom-width:0px;\"><\/span><em><span style=\"color: #bc2f54;\">Criar-um-Sim<\/span><\/em><\/strong><\/h4>\n<p>Adicionado um novo bot\u00e3o que permite aos jogadores aleatorizarem os tra\u00e7os de personalidade dos Sims.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.giphy.com\/media\/UQ7AUOIxVmyzEGPrUc\/giphy.gif\" alt=\"Sims 4 Conte\u00fado Atualiza\u00e7\u00e3o Junho 2019\" width=\"334\" height=\"166\" \/><\/p>\n<p>Adicionado um novo recurso que permite aos jogadores vinculares as altera\u00e7\u00f5es feitas nos Sims em ambas as suas formas, seja sobrenatural ou sim comum.<\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-1p.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10403 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-1p-300x254.jpg\" alt=\"\" width=\"300\" height=\"254\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-1p-300x254.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-1p.jpg 379w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Novas pe\u00e7as de roupas inspiradas na comunidade LGBTQ+, sendo 1 parte superior 1 cal\u00e7a legging para mulheres, e 1 camiseta para homens. (Poss\u00edvel utilizar livremente independente do g\u00eanero).<\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10404 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-2.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a> <a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10405 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-3.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a> <a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10406 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-4.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>V\u00e1rias novas estampas para modelo de fraudas de beb\u00eas.<\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10407 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-5.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\">\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<\/h4>\n<h4 style=\"text-align: center;\"><em><span style=\"color: #bc2f54;\">Modo Constru\u00e7\u00e3o<\/span><\/em><\/h4>\n<p>Uma espregui\u00e7adeira que se chama &#8220;Div\u00e3 Port\u00e1til&#8221;.<\/p>\n<div id='gallery-1' class='gallery galleryid-9753 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-20.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-19.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Bandeira do orgulho para o p\u00fablico LGBTQ+.<\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10409 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-8.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Nova categoria para decora\u00e7\u00f5es de teto.<\/p>\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-10423 aligncenter\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-1024x576.jpg\" alt=\"\" width=\"650\" height=\"366\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-13.jpg 1920w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>Dois novos tipos de funda\u00e7\u00f5es, sendo uma de palafitas redondas e outra de palafitas quadradas.<\/p>\n<div id='gallery-2' class='gallery galleryid-9753 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-9.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-10.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-11.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-12.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<ul>\n<li><em><strong>Adicionado tamb\u00e9m novas 350 estampas de cores para portas.<\/strong><\/em><\/li>\n<\/ul>\n<h4 style=\"text-align: center;\"><em><span style=\"color: #bc2f54;\">Caracter\u00edsticas de Lote<\/span><\/em><\/h4>\n<p>Dois novos tra\u00e7os de lote, roupas opcionais e Fora da Rede.<\/p>\n<div id='gallery-3' class='gallery galleryid-9753 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"449\" height=\"147\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-6.jpg 449w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-6-300x98.jpg 300w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"184\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-7.jpg 334w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-7-300x165.jpg 300w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\"><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h4 style=\"text-align: center;\">\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t<\/h4>\n<h4 style=\"text-align: center;\"><span style=\"color: #bc2f54;\"><em>Modo Simula\u00e7\u00e3o<\/em><\/span><\/h4>\n<p>Nova intera\u00e7\u00e3o &#8220;boiar&#8221; dispon\u00edvel agora em piscinas. Al\u00e9m disso, melhorias de nata\u00e7\u00e3o foram adicionadas, como a possibilidade dos Sims sentirem c\u00e3ibras ou perderem seus trajes de banho.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.giphy.com\/media\/MXEPR7pDBhTZcBoLIF\/giphy.gif\" alt=\"Sims 4 Conte\u00fado Atualiza\u00e7\u00e3o Junho 2019\" width=\"480\" height=\"270\" \/><\/p>\n<p>Ventiladores de teto agora firam no sentido correto (sim, antes eles giravam em sentido anti-hor\u00e1rio), e se voc\u00ea possui a expans\u00e3o Esta\u00e7\u00f5es instalada, eles servir\u00e3o para refrigerarem os Sims no calor, e tamb\u00e9m secarem Sims que estiverem \u00famidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.giphy.com\/media\/RlC83jkAC3iL3przf3\/giphy.gif\" alt=\"Sims 4 Conte\u00fado Atualiza\u00e7\u00e3o Junho 2019\" width=\"480\" height=\"270\" \/><\/p>\n<h4 style=\"text-align: center;\"><em><span style=\"color: #bc2f54;\"><strong>Careers<\/strong><\/span><\/em><\/h4>\n<p>Carreiras de meio per\u00edodo\u00a0 agora foram inclu\u00eddas tamb\u00e9m para Sims adultos, elas s\u00e3o: Babysitter (Bab\u00e1), Barista, Funcion\u00e1rio de Fast Food, Trabalho Manual e Comerci\u00e1rio.<\/p>\n<div id='gallery-4' class='gallery galleryid-9753 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-17.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-16.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-14.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-15.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-10418\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-1024x576.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-300x169.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-768x432.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-1536x864.jpg 1536w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18-390x220.jpg 390w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/Atualizacao-Junho-2019-Ilhas-18.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A atualiza\u00e7\u00e3o de junho, lan\u00e7ada hoje (18), adicionou n\u00e3o apenas novas roupas ao The Sims 4, como tamb\u00e9m novos itens, intera\u00e7\u00f5es e at\u00e9 mesmo novas carreiras. Confira abaixo tudo o que chegou ao jogo: Criar-um-Sim Adicionado um novo bot\u00e3o que permite aos jogadores aleatorizarem os tra\u00e7os de personalidade dos Sims. Adicionado um novo recurso que &hellip;<\/p>","protected":false},"author":5,"featured_media":10421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[142,6],"tags":[141,52,53,127,222,7],"class_list":["post-9753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analises","category-thesims4","tag-analise","tag-atualizacao-de-jogo","tag-conteudo-gratuito","tag-destaques","tag-lgbtq","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/en\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg",950,499,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-150x150.jpeg",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-300x158.jpeg",300,158,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-768x403.jpeg",768,403,true],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg",950,499,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg",950,499,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg",950,499,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais.jpeg",18,9,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-220x150.jpeg",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-390x220.jpeg",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/06\/capa-analise-atualizacao-junho-2019-ilhas-tropicais-780x470.jpeg",780,470,true]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/en\/author\/simstime\/"},"uagb_comment_info":5,"uagb_excerpt":"A atualiza\u00e7\u00e3o de junho, lan\u00e7ada hoje (18), adicionou n\u00e3o apenas novas roupas ao The Sims 4, como tamb\u00e9m novos itens, intera\u00e7\u00f5es e at\u00e9 mesmo novas carreiras. Confira abaixo tudo o que chegou ao jogo: Criar-um-Sim Adicionado um novo bot\u00e3o que permite aos jogadores aleatorizarem os tra\u00e7os de personalidade dos Sims. Adicionado um novo recurso que&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/9753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/comments?post=9753"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/9753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media\/10421"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media?parent=9753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/categories?post=9753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/tags?post=9753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}