{"id":57474,"date":"2026-01-12T16:31:05","date_gmt":"2026-01-12T19:31:05","guid":{"rendered":"https:\/\/simstime.net\/?p=57474"},"modified":"2026-01-12T16:31:13","modified_gmt":"2026-01-12T19:31:13","slug":"the-sims-4-anuncia-colaboracao-a-coach","status":"publish","type":"post","link":"https:\/\/simstime.net\/en\/2026\/01\/12\/the-sims-4-anuncia-colaboracao-a-coach\/","title":{"rendered":"The Sims 4 Anuncia Colabora\u00e7\u00e3o a Coach"},"content":{"rendered":"<p>A EA anunciou hoje uma colabora\u00e7\u00e3o especial para o The Sims 4, em parceria com a marca de moda Coach. Essa iniciativa traz a Cole\u00e7\u00e3o Coach, um conjunto de itens gratuitos que chega gratuitamente ao jogo em 13 de janeiro de 2026. <\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>A cole\u00e7\u00e3o inclui roupas, acess\u00f3rios e objetos decorativos inspirados em pe\u00e7as reais da Coach, al\u00e9m de novos conte\u00fados para a Galeria, celebrando valores compartilhados como individualidade, inclus\u00e3o e express\u00e3o pessoal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:28px\">\ud83d\udc62 Cole\u00e7\u00e3o Coach Chega em 13 de Janeiro<\/h2>\n\n\n\n<p><strong>A Cole\u00e7\u00e3o Coach,<\/strong>\u00a0que disponibiliza nove itens novos, chegar\u00e1 gratuitamente ao\u00a0<em>The Sims 4<\/em>\u00a0em 13 de janeiro de 2026, trazendo aprimoramentos de estilo inesperados para os seus Sims.<\/p>\n\n\n\n<p>Ela inclui itens b\u00e1sicos de vestu\u00e1rio, pe\u00e7as de impacto ousadas e decora\u00e7\u00f5es com o acabamento exclusivo da Coach, trazendo luxo casual para o Criar um Sim e o modo Constru\u00e7\u00e3o\/Compra.&nbsp;<\/p>\n\n\n\n<p>Veja o que estar\u00e1 dispon\u00edvel no jogo b\u00e1sico para a comunidade toda:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Explore estilos no\u00a0<strong>Criar um Sim<\/strong>\u00a0inspirados por pe\u00e7as favoritas da Coach, como os t\u00eanis &#8220;Soho&#8221;, as jaquetas &#8220;Varsity&#8221; e saias elegantes.<\/li>\n\n\n\n<li>D\u00ea os toques finais perfeitos para qualquer espa\u00e7o no\u00a0<strong>Modo Constru\u00e7\u00e3o\/Compra<\/strong>, com itens de decora\u00e7\u00e3o ic\u00f4nicos, desde o ba\u00fa tradicional da marca \u00e0s bolsas &#8220;Tabby&#8221; e &#8220;Brooklyn&#8221; da Coach.<\/li>\n\n\n\n<li>Uma\u00a0<strong>nova Fam\u00edlia\/Grupo na Galeria<\/strong>:\u00a0<em>Cocheira<\/em>. Tr\u00eas amizades em busca de grandes sonhos, muito estilo e uma pitada de drama.<\/li>\n<\/ul>\n\n\n\n<p>Tudo nesta colabora\u00e7\u00e3o celebra o que a Coach e o&nbsp;<em>The Sims<\/em>&nbsp;t\u00eam em comum: criatividade, individualidade, inclus\u00e3o e uma atitude divertida.&nbsp;<\/p>\n\n\n\n<p>Agora, vamos conferir como a maestria ic\u00f4nica da Coach se encontra com o estilo inconfund\u00edvel do&nbsp;<em>The Sims<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls poster=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-thumbnail-video.webp\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:20px\">\ud83d\udc60 <strong>Sims. Com a Coach.<\/strong><\/p>\n\n\n\n<p>Com todo o charme da Coach, estes novos itens do Criar um Sim d\u00e3o um toque luxuoso e pr\u00e1tico a visuais casuais, moda noturna e muito mais. Seus Sims v\u00e3o chamar a aten\u00e7\u00e3o onde estiverem, seja relaxando em casa ou curtindo uma festa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-1024x576.webp\" alt=\"The Sims 4 Anuncia Colabora\u00e7\u00e3o a Coach\" class=\"wp-image-57478\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n\t\t<div class=\"stream-item stream-item-in-post stream-item-in-post-3\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-7325551556070140\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<!-- Bloco 1 Responsivo 2026 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7325551556070140\"\r\n     data-ad-slot=\"6315654613\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n\t\t<\/div>\n\t\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:20px\">\ud83d\udc5c <strong>Acess\u00f3rios para o cotidiano<\/strong><\/p>\n\n\n\n<p>Para Simmers que acham que acess\u00f3rios s\u00e3o o grande destaque dos visuais&nbsp;<em>e<\/em>&nbsp;dos ambientes, os novos itens de decora\u00e7\u00e3o proporcionam uma eleg\u00e2ncia atemporal a qualquer lar. O renomado ba\u00fa da Coach \u00e9 uma obra de arte, al\u00e9m de uma pe\u00e7a central caracter\u00edstica do Modo Constru\u00e7\u00e3o\/Compra, enquanto as Bolsas &#8220;Tabby&#8221; e &#8220;Brooklyn&#8221; da Coach d\u00e3o a qualquer ambiente um toque elegante e cheio de personalidade.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-1024x576.webp\" alt=\"The Sims 4 Anuncia Colabora\u00e7\u00e3o a Coach\" class=\"wp-image-57479\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-3.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Exiba seus itens estilosos com o c\u00f4modo &#8220;Na Bolsa&#8221;, um espa\u00e7o onde o charme encontra a magia Simlish. Este c\u00f4modo, dispon\u00edvel para download na Galeria do&nbsp;<em>The Sims 4<\/em>, foi produzido cuidadosamente para exibir bolsas e ba\u00fas da Coach, al\u00e9m de oferecer um espa\u00e7o para quem \u00e9 f\u00e3 da marca se vestir e viver suas fantasias relacionadas \u00e0 moda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-1024x576.webp\" alt=\"The Sims 4 Anuncia Colabora\u00e7\u00e3o a Coach\" class=\"wp-image-57477\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-1024x576.webp 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-300x169.webp 300w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-768x432.webp 768w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-18x10.webp 18w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1-390x220.webp 390w, https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:20px\">\ud83c\udfd9\ufe0f <strong>Cocheira<\/strong><\/p>\n\n\n\n<p>Boas-vindas \u00e0&nbsp;<strong>Cocheira<\/strong>, onde a amizade, a ambi\u00e7\u00e3o e o caos fashionista de vanguarda coexistem debaixo de um s\u00f3 teto cheio de estilo. Conhe\u00e7a os colegas de quarto cuja confian\u00e7a parece ter sido feita sob medida:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Jonie Bag (Ele\/Dele)<\/strong>\u00a0&#8211; Um m\u00fasico talentoso que frequenta a academia para garantir que as roupas sirvam com a precis\u00e3o que seu perfeccionismo demanda. Jonie adora S-Pop e Hip-Hop, mas basta tocar uma m\u00fasica pop diante dele para que seu lado esnobe chegue com tudo.\u00a0<\/li>\n\n\n\n<li><strong>Brooke Lynne (Elu\/Delu)<\/strong>\u00a0&#8211; Esta pessoa descolada trabalha em um restaurante de fast food e fica feliz mesmo quando est\u00e1 tocando um instrumento ou jogando videogame. Apesar da energia paqueradora, mas leal de Brooke gerar uma aura magn\u00e9tica, a aus\u00eancia do amor faz sua melancolia aflorar.\u00a0<\/li>\n\n\n\n<li><strong>Selena Zhiwei (Ela\/Dela)<\/strong>\u00a0&#8211; Confiante, esperta e refinada at\u00e9 dizer chega, Selena \u00e9 uma rom\u00e2ntica incorrig\u00edvel \u00e0 procura de sua alma g\u00eamea. Esta artista aut\u00f4noma sempre tem tempo para comer algo gostoso, jogar videogame e pregar pe\u00e7as.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Fa\u00e7a download do lote Cocheira e do c\u00f4modo Na Bolsa na Galeria do&nbsp;<em>The Sims 4<\/em>&nbsp;e mostre os visuais que voc\u00ea criou com a hashtag&nbsp;<strong>#CoachxTheSims<\/strong>.<\/p>\n\n\n\n<p>A\u00a0<strong>Cole\u00e7\u00e3o Coach<\/strong>\u00a0estar\u00e1 dispon\u00edvel no\u00a0<em>The Sims 4<\/em>\u00a0a partir de 13 de janeiro de 2026!\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Com a chegada da Cole\u00e7\u00e3o Coach, o The Sims 4 ganha mais op\u00e7\u00f5es para quem gosta de moda e decora\u00e7\u00e3o no jogo base.<\/p>","protected":false},"excerpt":{"rendered":"<p>A EA anunciou hoje uma colabora\u00e7\u00e3o especial para o The Sims 4, em parceria com a marca de moda Coach. Essa iniciativa traz a Cole\u00e7\u00e3o Coach, um conjunto de itens gratuitos que chega gratuitamente ao jogo em 13 de janeiro de 2026. A cole\u00e7\u00e3o inclui roupas, acess\u00f3rios e objetos decorativos inspirados em pe\u00e7as reais da &hellip;<\/p>","protected":false},"author":7,"featured_media":57476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[77,6],"tags":[174,127,7],"class_list":["post-57474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parcerias-the-sims","category-thesims4","tag-colaboracoes","tag-destaques","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa.webp","author_info":{"display_name":"Weslley","author_link":"https:\/\/simstime.net\/en\/author\/weslley-luzzi\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa.webp","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa.webp",1200,675,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-150x150.webp",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-300x169.webp",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-768x432.webp",768,432,true],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-1024x576.webp",1024,576,true],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa.webp",1200,675,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa.webp",1200,675,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-18x10.webp",18,10,true],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-220x150.webp",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-390x220.webp",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2026\/01\/the-sims-4-anuncia-colaboracao-com-a-coach-capa-780x470.webp",780,470,true]},"uagb_author_info":{"display_name":"Weslley","author_link":"https:\/\/simstime.net\/en\/author\/weslley-luzzi\/"},"uagb_comment_info":0,"uagb_excerpt":"A EA anunciou hoje uma colabora\u00e7\u00e3o especial para o The Sims 4, em parceria com a marca de moda Coach. Essa iniciativa traz a Cole\u00e7\u00e3o Coach, um conjunto de itens gratuitos que chega gratuitamente ao jogo em 13 de janeiro de 2026. A cole\u00e7\u00e3o inclui roupas, acess\u00f3rios e objetos decorativos inspirados em pe\u00e7as reais da&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/57474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/comments?post=57474"}],"version-history":[{"count":5,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/57474\/revisions"}],"predecessor-version":[{"id":57488,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/57474\/revisions\/57488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media\/57476"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media?parent=57474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/categories?post=57474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/tags?post=57474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}