{"id":10767,"date":"2019-07-11T19:14:47","date_gmt":"2019-07-11T22:14:47","guid":{"rendered":"https:\/\/simstime.com.br\/?p=10767"},"modified":"2022-12-11T04:26:42","modified_gmt":"2022-12-11T07:26:42","slug":"proxima-expansao-do-the-sims-4-pode-ser-lancada-ate-o-fim-do-ano","status":"publish","type":"post","link":"https:\/\/simstime.net\/en\/2019\/07\/11\/proxima-expansao-do-the-sims-4-pode-ser-lancada-ate-o-fim-do-ano\/","title":{"rendered":"Pr\u00f3xima Expans\u00e3o do The Sims 4 Pode Ser Lan\u00e7ada At\u00e9 o Fim do Ano"},"content":{"rendered":"<p>O f\u00e3 site <strong><a href=\"https:\/\/simscommunity.info\/2019\/07\/11\/the-sims-4s-8th-expansion-pack-to-release-by-the-end-of-2019\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sims Community<\/a><\/strong> encontrou dados que podem indicar o desenvolvimento de um novo pacote de expans\u00e3o para o The Sims 4, o qual poderia estar planejado para ser lan\u00e7ado ainda no ano de 2019.<\/p>\n<span class=\"\" style=\"display:block;clear:both;height: 0px;padding-top: 6px;border-top-width:0px;border-bottom-width:0px;\"><\/span>As informa\u00e7\u00f5es vem diretamente do site de carreiras da EA, onde h\u00e1 uma vaga de emprego em que procuram por um editor de voz que colabore na mixagem e entrega de \u00e1udios e sons para a pr\u00f3ximo<strong><em> Expansion Pack<\/em><\/strong> do The Sims 4.<\/p>\n<p>A vaga de emprego tem um prazo de validade que vai do dia 8 de julho \u00e0 11 de outubro, o que significa que n\u00e3o est\u00e1 relacionado ao pacote de Jogo &#8220;Reino de Magia&#8221;.<\/p>\n<blockquote class=\"quote-light\"><p><span style=\"font-size: 16px;\">Localiza\u00e7\u00e3o: Redwood Shores, CA<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Prazo: 08 de julho\u00a0 &#8211; 11 de outubro<\/span><\/p>\n<p><span style=\"font-size: 16px;\">A Maxis Studio da Electronic Arts est\u00e1 procurando por um editor de voz para se juntar \u00e0 equipe de \u00e1udio e colaborar com o lan\u00e7amento de um pacote de expans\u00e3o para o The Sims 4.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">O candidato ideal deve ter experi\u00eancia em fornecer \u00e1udio de qualidade final ou \u00e1udios provis\u00f3rios feitos em software. Fortes habilidades interpessoais e capacidade de trabalhar dentro das limita\u00e7\u00f5es t\u00e9cnicas para fornecer \u00e1udio de qualidade que sejam essenciais. Tamb\u00e9m \u00e9 importante que o candidato entenda o papel do \u00e1udio nos videogames; criando conte\u00fado final para a melhor experi\u00eancia do jogador.<\/span><\/p>\n<p><span style=\"font-size: 16px;\">Habilidades necess\u00e1rias:<\/span><\/p>\n<ul>\n<li><span style=\"font-size: 16px;\">Experi\u00eancia em edi\u00e7\u00e3o de voz e experi\u00eancia em pacotes de software relevantes, como Logic Audio, Sound Forge e ProTools.<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Experi\u00eancia com todos os aspectos de dire\u00e7\u00e3o de voz para produ\u00e7\u00e3o de jogos, com profici\u00eancia em dire\u00e7\u00e3o de voz envolvendo os principais atores profissionais e instru\u00e7\u00f5es de implementa\u00e7\u00e3o de jogos. Profici\u00eancia com ferramentas de \u00e1udio padr\u00e3o (DAW, edi\u00e7\u00e3o, plugins, etc) e ferramentas de est\u00fadio (microfone, compressores, etc).<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Profici\u00eancia em plataformas PC e Mac e conforto com ferramentas personalizadas.<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Experi\u00eancia com Produ\u00e7\u00e3o e Design de Jogos.<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Um ouvido comprometido com a experi\u00eancia do usu\u00e1rio e que valorize os detalhes.<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Uma mente aberta, disposta a desafiar a sabedoria convencional e encontrar solu\u00e7\u00f5es criativas para os nossos problemas \u00fanicos.<\/span><\/li>\n<li><span style=\"font-size: 16px;\">Um olhar inovador em tecnologia de \u00e1udio e ferramentas de voz.<br \/>\n<\/span><\/li>\n<li>Que seja flex\u00edvel em rela\u00e7\u00e3o a r\u00e1pidas mudan\u00e7as entre projetos e fun\u00e7\u00f5es.<\/li>\n<li><span style=\"font-size: 16px;\"><span style=\"font-size: 16px;\"><span style=\"font-size: 16px;\">Ser algu\u00e9m que possa prosperar e crescer em um ambiente din\u00e2mico e trazer entusiasmo para aqueles que o rodeiam.<\/span><\/span><\/span>&nbsp;\n<figure id=\"attachment_10768\" aria-describedby=\"caption-attachment-10768\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10768 size-large\" src=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego-1024x657.jpg\" alt=\"\" width=\"1024\" height=\"657\" srcset=\"https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego-1024x657.jpg 1024w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego-300x193.jpg 300w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego-768x493.jpg 768w, https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/Imagem-vaga-de-Emprego.jpg 1215w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption id=\"caption-attachment-10768\" class=\"wp-caption-text\">Captura de tela feita por SimsCommunity.Info<\/figcaption><\/figure><\/li>\n<\/ul>\n<\/blockquote>\n<p>\u00c9 importante ressaltar novamente que esta vaga de emprego \u00e9 sobre Pacote de Expans\u00e3o, a n\u00e3o possui qualquer rela\u00e7\u00e3o com outros jogos anunciados no \u00faltimo m\u00eas, como o The Sims 4 Reino de Magia Pacote de Jogo e The Sims 4 Moschino.<\/p>\n<p>A possibilidade desta expans\u00e3o ser lan\u00e7ada ainda no final do ano tem a ver com o processo de edi\u00e7\u00e3o de \u00e1udio, que normalmente \u00e9 um dos \u00faltimos passos no desenvolvimento de um novo pacote para o The Sims 4.<\/p>","protected":false},"excerpt":{"rendered":"<p>O f\u00e3 site Sims Community encontrou dados que podem indicar o desenvolvimento de um novo pacote de expans\u00e3o para o The Sims 4, o qual poderia estar planejado para ser lan\u00e7ado ainda no ano de 2019. As informa\u00e7\u00f5es vem diretamente do site de carreiras da EA, onde h\u00e1 uma vaga de emprego em que procuram &hellip;<\/p>","protected":false},"author":5,"featured_media":10769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[27,6],"tags":[26,5,7],"class_list":["post-10767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rumores","category-thesims4","tag-especulacao","tag-pacote-de-expansao","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/en\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg",950,499,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-150x150.jpg",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-300x158.jpg",300,158,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-768x403.jpg",768,403,true],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg",950,499,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg",950,499,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg",950,499,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao.jpg",18,9,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-220x150.jpg",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-390x220.jpg",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2019\/07\/The-Sims-4-Expansao-780x470.jpg",780,470,true]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/en\/author\/simstime\/"},"uagb_comment_info":0,"uagb_excerpt":"O f\u00e3 site Sims Community encontrou dados que podem indicar o desenvolvimento de um novo pacote de expans\u00e3o para o The Sims 4, o qual poderia estar planejado para ser lan\u00e7ado ainda no ano de 2019. As informa\u00e7\u00f5es vem diretamente do site de carreiras da EA, onde h\u00e1 uma vaga de emprego em que procuram&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/10767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/comments?post=10767"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/posts\/10767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media\/10769"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/media?parent=10767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/categories?post=10767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/en\/wp-json\/wp\/v2\/tags?post=10767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}