{"id":45717,"date":"2023-10-25T14:18:31","date_gmt":"2023-10-25T17:18:31","guid":{"rendered":"https:\/\/simstime.net\/?p=45717"},"modified":"2023-10-25T14:18:31","modified_gmt":"2023-10-25T17:18:31","slug":"vazou-the-sims-4-casas-de-aluguel-deve-ser-proxima-expansao","status":"publish","type":"post","link":"https:\/\/simstime.net\/de\/2023\/10\/25\/vazou-the-sims-4-casas-de-aluguel-deve-ser-proxima-expansao\/","title":{"rendered":"VAZOU: The Sims 4 Casas de Aluguel Deve Ser Pr\u00f3xima Expans\u00e3o"},"content":{"rendered":"<div class=\"box warning\">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>Por favor, encare todas as informa\u00e7\u00f5es desta publica\u00e7\u00e3o como rumor.\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n<p>A Instant Gaming, uma loja que vende jogos digitais para PC e Mac, publicou hoje uma <strong><a href=\"https:\/\/www.instant-gaming.com\/pt\/15236-comprar-ea-app-the-sims-4-rental-houses-pc-mac-jogo-ea-app\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina<\/a><\/strong> que revelou a tem\u00e1tica do pr\u00f3ximo Pacote de Expans\u00e3o do The Sims 4, o qual deve se chamar: The Sims 4 Rental Houses (The Sims 4 Casas de Aluguel em portugu\u00eas). O novo pacote est\u00e1 programado para ser lan\u00e7ado no dia 7 de dezembro de 2023, e daria aos jogadores a possibilidade de gerenciar im\u00f3veis, como alugar casas.<\/p>\n<p>A Instant Gaming \u00e9 bastante conhecida na comunidade The Sims por vazar a tem\u00e1tica de pacotes futuros que o The Sims 4 receber\u00e1, tendo j\u00e1 acertado anteriormente o lan\u00e7amento de expans\u00f5es como The Sims 4 A Aventura de Crescer e The Sims 4 Tomando as R\u00e9deas, portanto, as chances de que esse pacote seja real s\u00e3o bastante altas. Sobre a imagem utilizada para ilustrar o pacote, provavelmente se trata de algo provis\u00f3rio, criado pela pr\u00f3pria Instant Gaming, como j\u00e1 aconteceu em outras ocasi\u00f5es.<\/p>\n<p>A tem\u00e1tica de casas de aluguel tamb\u00e9m vai totalmente ao encontro das dicas fornecidas pelo \u00faltimo roteiro de lan\u00e7amentos do The Sims 4 para 2023, que revelava que a pr\u00f3xima expans\u00e3o seria sobre vizinhan\u00e7as, e tamb\u00e9m relacionametos entre vizinhos, veja mais <strong><a href=\"https:\/\/simstime.net\/de\/2023\/10\/09\/proxima-expansao-do-the-sims-4-sera-sobre-relacionamentos-com-vizinhos\/\" target=\"_blank\" rel=\"noopener\">clicando aqui.<\/a><\/strong><\/p>\n<p>Caso o The Sims 4 Casas de Aluguel seja realmente verdadeiro, ser\u00e1 surpreendente, visto que, apesar da funcionalidade de aluguel de casas ser um recurso solicitado h\u00e1 um bom tempo pela comunidade, isso n\u00e3o \u00e9 algo que estava entre as prioridades dos jogadores como um pacote de expans\u00e3o.<\/p>\n<hr \/>\n<p>O que voc\u00eas acharam? Gostaram da tem\u00e1tica da pr\u00f3xima expans\u00e3o do The Sims 4? Fiquem ligados no SimsTime para mais informa\u00e7\u00f5es.<\/p>","protected":false},"excerpt":{"rendered":"<p>Por favor, encare todas as informa\u00e7\u00f5es desta publica\u00e7\u00e3o como rumor. A Instant Gaming, uma loja que vende jogos digitais para PC e Mac, publicou hoje uma p\u00e1gina que revelou a tem\u00e1tica do pr\u00f3ximo Pacote de Expans\u00e3o do The Sims 4, o qual deve se chamar: The Sims 4 Rental Houses (The Sims 4 Casas de &hellip;<\/p>","protected":false},"author":5,"featured_media":45719,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[27,6],"tags":[127,26,5,7],"class_list":["post-45717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rumores","category-thesims4","tag-destaques","tag-especulacao","tag-pacote-de-expansao","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/de\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",774,435,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao-150x150.webp",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao-300x169.webp",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao-768x432.webp",768,432,true],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",774,435,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",774,435,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",774,435,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",18,10,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao-220x150.webp",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao-390x220.webp",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2023\/10\/vazou_thesims4_casas_de_aluguel_deve_ser_proxima_expansao.webp",774,435,false]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/de\/author\/simstime\/"},"uagb_comment_info":0,"uagb_excerpt":"Por favor, encare todas as informa\u00e7\u00f5es desta publica\u00e7\u00e3o como rumor. A Instant Gaming, uma loja que vende jogos digitais para PC e Mac, publicou hoje uma p\u00e1gina que revelou a tem\u00e1tica do pr\u00f3ximo Pacote de Expans\u00e3o do The Sims 4, o qual deve se chamar: The Sims 4 Rental Houses (The Sims 4 Casas de&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts\/45717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/comments?post=45717"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts\/45717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/media\/45719"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/media?parent=45717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/categories?post=45717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/tags?post=45717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}