{"id":30498,"date":"2022-01-05T15:59:39","date_gmt":"2022-01-05T18:59:39","guid":{"rendered":"https:\/\/simstime.net\/?p=30498"},"modified":"2022-11-08T22:47:38","modified_gmt":"2022-11-09T01:47:38","slug":"the-sims-4-pode-ganhar-pacote-de-jogo-sobre-casamentos","status":"publish","type":"post","link":"https:\/\/simstime.net\/de\/2022\/01\/05\/the-sims-4-pode-ganhar-pacote-de-jogo-sobre-casamentos\/","title":{"rendered":"The Sims 4 Pode Ganhar Pacote de Jogo sobre Casamentos"},"content":{"rendered":"<p>Ao longo dos anos, se tem uma coisa que a comunidade The Sims sempre pediu, \u00e9 por melhorias no sistema de casamentos da franquia The Sims. E n\u00e3o estamos falando apenas sobre The Sims 4, mas tamb\u00e9m de The Sims 3, The Sims 2, e inclusive The Sims 1.<\/p>\n<p>Quem \u00e9 que nunca se sentiu frustrado por tentar dar uma festa de casamento no The Sims, e as coisas sempre darem errado, como Sims deixando de se sentar em seus lugares no momento da cerim\u00f4nia, ou n\u00e3o agindo adequadamente de acordo com a ocasi\u00e3o? A verdade, \u00e9 que a mec\u00e2nica que casamentos no The Sims sempre foi negligenciada, e isso \u00e9 algo que se estende at\u00e9 os dias de hoje.<\/p>\n<p>\u00c9 incr\u00edvel pensar que mesmo ap\u00f3s 22 anos, situa\u00e7\u00f5es como Sims se casando no banheiro ou em uma cozinha ainda n\u00e3o coisas extremamente normais em um jogo que evoluiu dramaticamente em tantos aspectos, mas ainda peca por esquecer de aprimorar coisas t\u00e3o simples e corriqueiras.<\/p>\n<p>Mas felizmente, \u00e9 poss\u00edvel que todo o drama dos casamentos mal feitos esteja perto do fim. Hoje, a Equipe The Sims <strong><a href=\"https:\/\/simstime.net\/de\/2022\/01\/05\/the-sims-4-anuncia-novos-pacotes-e-conteudos-gratuitos\/\" target=\"_blank\" rel=\"noopener\">anunciou o seu novo cronograma de lan\u00e7amentos do The Sims 4<\/a><\/strong> para o pr\u00f3ximo trimestre de 2022, revelando uma s\u00e9rie de pacotes e novidades que estar\u00e3o chegando ao jogo, incluindo um novo Pacote de Jogo que &#8220;d\u00e1 uma festa de amor&#8221; de acordo com o an\u00fancio feito de forma impl\u00edcita.<\/p>\n<p>O tal Pacote de Jogo <em>&#8220;que d\u00e1 uma festa de amor&#8221;<\/em> ser\u00e1 o primeiro lan\u00e7amento do pr\u00f3ximo trimestre, sendo poss\u00edvel que seja lan\u00e7ado ainda em fevereiro de 2022. Quanto a isso, a comunidade neste momento j\u00e1 come\u00e7a a especular sobre a possibilidade de realmente se tratar de um pacote voltado a festas de casamentos para The Sims 4, sendo a tem\u00e1tica mais sugerida at\u00e9 agora.<\/p>\n<p>Levando em considera\u00e7\u00e3o o termo &#8220;festa de amor&#8221; e tamb\u00e9m algumas pesquisas feitas pela Equipe The Sims em que sugeria a cria\u00e7\u00e3o de um pacote sobre casamentos, \u00e9 muito prov\u00e1vel que realmente tenhamos um pacote voltado a essa celebra\u00e7\u00e3o, o que de certa forma, acaba sanando o desejo de muitos jogadores que h\u00e1 anos pedem por melhorias consistentes nas festas de casamento.<\/p>\n<p>Fiquem de olho nas pr\u00f3ximas not\u00edcias aqui do SimsTime!<\/p>","protected":false},"excerpt":{"rendered":"<p>Ao longo dos anos, se tem uma coisa que a comunidade The Sims sempre pediu, \u00e9 por melhorias no sistema de casamentos da franquia The Sims. E n\u00e3o estamos falando apenas sobre The Sims 4, mas tamb\u00e9m de The Sims 3, The Sims 2, e inclusive The Sims 1. Quem \u00e9 que nunca se sentiu &hellip;<\/p>","protected":false},"author":5,"featured_media":30500,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[27,6],"tags":[26,18,7],"class_list":["post-30498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rumores","category-thesims4","tag-especulacao","tag-pacote-de-jogo","tag-the-sims-4"],"featured_image_src":"https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png","author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/de\/author\/simstime\/"},"jetpack_featured_media_url":"https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png","uagb_featured_image_src":{"full":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false],"thumbnail":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1-150x150.png",150,150,true],"medium":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1-300x169.png",300,169,true],"medium_large":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false],"large":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false],"1536x1536":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false],"2048x2048":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false],"trp-custom-language-flag":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",18,10,false],"jannah-image-small":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1-220x150.png",220,150,true],"jannah-image-large":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1-390x220.png",390,220,true],"jannah-image-post":["https:\/\/simstime.net\/wp-content\/uploads\/2022\/01\/thesims4_pacote_de_casamentos_1.png",768,432,false]},"uagb_author_info":{"display_name":"SimsTime","author_link":"https:\/\/simstime.net\/de\/author\/simstime\/"},"uagb_comment_info":0,"uagb_excerpt":"Ao longo dos anos, se tem uma coisa que a comunidade The Sims sempre pediu, \u00e9 por melhorias no sistema de casamentos da franquia The Sims. E n\u00e3o estamos falando apenas sobre The Sims 4, mas tamb\u00e9m de The Sims 3, The Sims 2, e inclusive The Sims 1. Quem \u00e9 que nunca se sentiu&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts\/30498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/comments?post=30498"}],"version-history":[{"count":0,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/posts\/30498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/media\/30500"}],"wp:attachment":[{"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/media?parent=30498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/categories?post=30498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simstime.net\/de\/wp-json\/wp\/v2\/tags?post=30498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}